{"id":15464,"date":"2024-11-01T09:00:32","date_gmt":"2024-11-01T08:00:32","guid":{"rendered":"https:\/\/montecarloliving.com\/?p=15464"},"modified":"2024-10-30T17:44:17","modified_gmt":"2024-10-30T16:44:17","slug":"evenements-du-week-end-du-2-et-3-novembre-2024-nice","status":"publish","type":"post","link":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/","title":{"rendered":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice"},"content":{"rendered":"<p><strong>\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!<\/strong><\/p>\n<hr \/>\n<h4><strong>Atelier de calligraphie japonaise<\/strong><\/h4>\n<p>Samedi 2 novembre 2024 \u00e0 14h.<\/p>\n<p>\u00c0 l&rsquo;occasion de la pr\u00e9sence \u00e0 Nice des ma\u00eetres calligraphes Kinei Akamatsu et Cheiko Imamura, le Mus\u00e9e des Arts Asiatiques offre au public un moment unique de d\u00e9couverte de cet art traditionnel impr\u00e9gn\u00e9 de spiritualit\u00e9 Zen.<\/p>\n<p><a href=\"https:\/\/maa.departement06.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/maa.departement06.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>F\u00eate des morts<\/strong><\/h4>\n<p>Samedi 2 novembre 2024 \u00e0 18h.<\/p>\n<p>\u00c0 l&rsquo;occasion de la Comm\u00e9moration des d\u00e9funts, participez \u00e0 des ateliers et des activit\u00e9s pour d\u00e9couvrir la culture mexicaine.<br \/>\nL&rsquo;atelier mettra en avant les traditions mexicaines de mani\u00e8re ludique et cr\u00e9ative.<\/p>\n<p><a href=\"https:\/\/www.explorenicecotedazur.com\/fr\/fiche\/fete-des-morts-it\/\">https:\/\/www.explorenicecotedazur.com\/fr\/fiche\/fete-des-morts-it\/<\/a><\/p>\n<hr \/>\n<h4><strong>Vieux mill\u00e9simes<\/strong><\/h4>\n<p>Du samedi 2 au dimanche 3 novembre 2024 de 10h \u00e0 18h. Ventes exceptionnelles de vins APO Bellet au Domaine de la Source.<\/p>\n<p>Ne manquez pas cette occasion unique d&rsquo;acqu\u00e9rir nos vieux mill\u00e9simes. Profitez des vins conserv\u00e9s dans des conditions exceptionnelles.<\/p>\n<p><a href=\"https:\/\/domainedelasource.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/domainedelasource.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Marathon des Alpes-Maritimes Nice-Cannes<\/strong><\/h4>\n<p>Dimanche 3 novembre 2024.<\/p>\n<p>Entrez dans la l\u00e9gende du premier marathon de France apr\u00e8s Paris et profitez de la mer, des palmiers et du soleil de la C\u00f4te d&rsquo;Azur le temps d&rsquo;un week-end !<\/p>\n<p>Ce parcours de 42 km longe la mer, de Nice \u00e0 Cannes, et vous invite \u00e0 d\u00e9couvrir les villes de : Saint Laurent-du-Var, Cagnes-sur-Mer, Villeneuve-Loubet, Antibes Juan-les-Pins et Vallauris Golfe-Juan&#8230;<\/p>\n<p><a href=\"https:\/\/www.marathon06.com\/2024\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.marathon06.com\/2024\/<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition Nice, ma ville, mon quartier<\/strong><\/h4>\n<p>Du 18\/10\/2024 au 02\/03\/2025 Heures d&rsquo;ouverture : lundi, mercredi, jeudi, vendredi, samedi et dimanche de 11h \u00e0 18h, sauf le 1er janvier et le 25 d\u00e9cembre.<\/p>\n<p>Inspir\u00e9e des mots de Patrick Modiano, cette exposition propose de revisiter la ville \u00e0 travers le prisme de ses quartiers, ces espaces \u00e0 la crois\u00e9e de l&rsquo;intime et du collectif, du pass\u00e9 et du pr\u00e9sent.<\/p>\n<p><a href=\"https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/musee-massena-le-musee\" target=\"_new\" rel=\"noopener\">https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/musee-massena-le-musee<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition J\u00e9r\u00e9my Griffaud, \u201cSous le Ciel\u201d<\/strong><\/h4>\n<p>Du 12\/10\/2024 au 20\/01\/2025 de 10h \u00e0 18h, sauf le 1er janvier et le 25 d\u00e9cembre. Ferm\u00e9 le mardi.<\/p>\n<p>Con\u00e7ue pour faire \u00e9cho \u00e0 l\u2019\u0153uvre de Chagall, l&rsquo;exposition intitul\u00e9e \u00ab\u00a0Sous le Ciel\u00a0\u00bb se pr\u00e9sente comme une nouvelle exp\u00e9rience picturale, entre mat\u00e9rialit\u00e9 et langage symbolique, tous deux renforc\u00e9s par l&rsquo;apport de la technologie num\u00e9rique.<\/p>\n<p><a href=\"https:\/\/musees-nationaux-alpesmaritimes.fr\/chagall\/\" target=\"_new\" rel=\"noopener\">https:\/\/musees-nationaux-alpesmaritimes.fr\/chagall\/<\/a><\/p>\n<hr \/>\n<h4><strong>Spectacle R\u00e9veillon \u00e0 la morgue<\/strong><\/h4>\n<p>Du 12\/10\/2024 au 04\/05\/2025, tous les jours.<\/p>\n<p>Spectacle dirig\u00e9 par S\u00e9bastien Morena.<\/p>\n<p>C\u2019est la nuit de la Saint-Sylvestre, un homme est de garde \u00e0 l\u2019Institut M\u00e9dico-L\u00e9gal avec pour seule compagnie des \u00e9clairs et le repas pr\u00e9par\u00e9 par sa m\u00e8re.<\/p>\n<p>Une heure avant minuit, une femme appara\u00eet devant lui, couverte uniquement d\u2019un drap. Qui est-elle ? D\u2019o\u00f9 vient-elle ? Elle-m\u00eame ne le sait pas&#8230; mais le tiroir n\u00b099 est ouvert et son occupant a disparu !!<\/p>\n<p><a href=\"https:\/\/www.theatrenice.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.theatrenice.fr\/<\/a><\/p>\n<hr \/>\n<p><strong>Spectacle Th\u00e9\u00e2tral Le malade imaginaire<\/strong><\/p>\n<p>Du 06\/10\/2024 au 31\/05\/2025, tous les jours.<\/p>\n<p>Spectacle th\u00e9\u00e2tral de Moli\u00e8re dirig\u00e9 par S\u00e9bastien Morena.<\/p>\n<p>Argan, veuf et hypocondriaque, se remarie avec B\u00e9line qui feint des soins attentifs mais esp\u00e8re uniquement la mort de son mari pour h\u00e9riter. Il subit saign\u00e9es, purges et de nombreux autres rem\u00e8des prescrits par des m\u00e9decins avides de lui plaire dans ses d\u00e9lires&#8230; et surtout de toucher leur pension !<\/p>\n<p><a href=\"https:\/\/www.theatrenice.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.theatrenice.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Sweet days of Discipline<\/strong><\/h4>\n<p>Du 27\/09\/2024 au 02\/02\/2025<br \/>\nHoraires d&rsquo;ouverture : lundi, mercredi, jeudi, vendredi, samedi et dimanche de 14h \u00e0 18h.<\/p>\n<p>\u00ab Sweet Days of Discipline \u00bb est une exposition qui r\u00e9unit les 44 artistes dipl\u00f4m\u00e9s de Villa Arson en 2023. Elle est organis\u00e9e par les r\u00e9dacteurs (Alice Dusapin, Martin Laborde et Baptiste Pinteaux) de la revue d&rsquo;art octopus notes.<\/p>\n<p>\u00ab Comment vous \u00eates-vous sentis un an apr\u00e8s avoir quitt\u00e9 l&rsquo;\u00e9cole ? Comment \u00e9tait votre vie ? Qu&rsquo;est-ce qui peut relier 44 artistes dipl\u00f4m\u00e9s il y a seulement un an ? \u00bb Pour nous aider \u00e0 r\u00e9pondre \u00e0 ces questions, nous avons demand\u00e9 \u00e0 certains artistes dont les pratiques r\u00e9sonnent avec celles expos\u00e9es dans l&rsquo;exposition.<\/p>\n<p><a href=\"https:\/\/villa-arson.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/villa-arson.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Th\u00e9\u00e2tre &#8211; Un animal de compagnie<\/strong><\/h4>\n<p>Du 28\/09 au 07\/12\/2024, tous les jours.<\/p>\n<p>Spectacle th\u00e9\u00e2tral de Francis Veber. Mise en sc\u00e8ne par la Compagnie S\u00e9rie illimit\u00e9e.<\/p>\n<p>Un couple. Christine : d\u00e9coratrice. Henri : journaliste. Mari\u00e9s depuis 20 ans.<\/p>\n<p>Il voulait un enfant, elle pr\u00e9f\u00e9rait donner la priorit\u00e9 \u00e0 sa carri\u00e8re. Quand elle s\u2019est d\u00e9cid\u00e9e, c\u2019\u00e9tait trop tard. Alors elle a demand\u00e9 \u00e0 Henri de lui offrir un Yorkshire pour compenser sa frustration.<\/p>\n<p><a href=\"https:\/\/www.billetreduc.com\/v2\/PurchaseTunnel#\/ShowSelection?eventId=316636\" target=\"_new\" rel=\"noopener\">https:\/\/www.billetreduc.com\/v2\/PurchaseTunnel#\/ShowSelection?eventId=316636<\/a><\/p>\n<hr \/>\n<h4><strong>Ashes of the Arabian\u2019s Pearl \u2013 Valentin Valette<\/strong><\/h4>\n<p>Du 28\/09 au 03\/11\/2024<br \/>\nHoraires d&rsquo;ouverture : mardi, mercredi, jeudi, vendredi, samedi et dimanche de 10h \u00e0 12h30 et de 13h30 \u00e0 18h.<\/p>\n<p>La Galerie du Mus\u00e9e pr\u00e9sente l&rsquo;exposition du photographe Valentin Valette, laur\u00e9at du Prix Satellite 2024, dans le cadre du festival L&rsquo;IMAGE_SATELLITE.<\/p>\n<p><a href=\"https:\/\/museephotographie.nice.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/museephotographie.nice.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition \u2013 J\u00e0nluc Sauvaigo \u2013 Les 36 vues du Mont Chauve<\/strong><\/h4>\n<p>Du 16\/05 au 30\/11\/2024, tous les jours.<\/p>\n<p>Entre 2004 et 2010, J\u00e0nluc Sauvaigo a illustr\u00e9 une s\u00e9rie de croquis de l&rsquo;\u00ab Histoire populaire nissarde \u00bb, se d\u00e9roulant sur le Mont Chauve, ainsi sont n\u00e9es les 36 vues du Mont Chauve.<\/p>\n<p>La premi\u00e8re carte s&rsquo;inspire d&rsquo;abord du peintre japonais Hiroshige, pour les autres, J\u00e0nluc Sauvaigo \u00e9voque Hokusai et ses c\u00e9l\u00e8bres Trente-six vues du Mont Fuji. L&rsquo;auteur dira : \u00ab\u00a0J&rsquo;ai voulu c\u00e9l\u00e9brer \u00e0 ma mani\u00e8re un lieu magique de la r\u00e9gion. Et \u00e0 Nice, le Mont Chauve \u00e9tait une \u00e9vidence. Il est visible depuis les bassins du Paillon et du Var, presque partout.\u00a0\u00bb<\/p>\n<p><a href=\"https:\/\/www.explorenicecotedazur.com\/it\/fiche\/exposition-janluc-sauvaigo-les-36-vues-du-mont-chauve-it\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.explorenicecotedazur.com\/it\/fiche\/exposition-janluc-sauvaigo-les-36-vues-du-mont-chauve-it\/<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition \u2013 Petite histoire de la biodiversit\u00e9<\/strong><\/h4>\n<p>Du 07\/06 au 10\/11\/2024, tous les jours.<\/p>\n<p>Le Mus\u00e9e vous invite \u00e0 une promenade naturaliste \u00e0 travers la plaine et la c\u00f4te pour d\u00e9couvrir les \u00ab tr\u00e9sors \u00bb de la biodiversit\u00e9 de cette r\u00e9gion, c\u00e9l\u00e8bre dans le monde entier pour ses paysages mi-marins, mi-alpins.<\/p>\n<p><a href=\"https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/museum-d-histoire-naturelle\" target=\"_new\" rel=\"noopener\">https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/museum-d-histoire-naturelle<\/a><\/p>\n<hr \/>\n<h4><strong>Dans l\u2019intimit\u00e9 des collections du Palais Lascaris<\/strong><\/h4>\n<p>Du 13\/07\/2024 au 10\/03\/2025<br \/>\nHoraires d&rsquo;ouverture : lundi, mercredi, jeudi, vendredi, samedi et dimanche de 10h \u00e0 18h, sauf le 1er janvier.<\/p>\n<p>Que se passe-t-il derri\u00e8re les grilles monumentales du Palais Lascaris quand il est ferm\u00e9 au public ?<\/p>\n<p>Pr\u00e9servation pr\u00e9ventive, restauration, corrections d\u2019\u00e9preuves\u2026 Ces activit\u00e9s men\u00e9es en coulisses sont souvent m\u00e9connues du public. Mais pour cette exposition, les agents du Palais Lascaris souhaitent partager leur passion et leur objet pr\u00e9f\u00e9r\u00e9, pour montrer au public leur quotidien.<\/p>\n<p><a href=\"https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/palais-lascaris-le-palais\" target=\"_new\" rel=\"noopener\">https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/palais-lascaris-le-palais<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition \u2013 Agap\u00e9. L\u2019amour qui change le Monde<\/strong><\/h4>\n<p>Du 15\/07 au 15\/12\/2024, tous les jours.<\/p>\n<p>La colline embl\u00e9matique du Ch\u00e2teau accueille une exposition monumentale de l\u2019artiste italien Andrea Roggi.<\/p>\n<p>Trois \u0153uvres, dont deux in\u00e9dites, \u00ab L\u2019Amour, le Futur du Monde \u00bb et \u00ab Le Futur c\u2019est Nous \u00bb, seront install\u00e9es dans le cadre naturel de la colline du Ch\u00e2teau et de la Baie des Anges. L\u2019exposition s\u2019inspire du concept grec de l\u2019amour, avec des sculptures monumentales en bronze repr\u00e9sentant la nature, parfaitement int\u00e9gr\u00e9es \u00e0 l\u2019environnement de Nice.<\/p>\n<p><a href=\"https:\/\/www.explorenicecotedazur.com\/it\/fiche\/exposition-agape-l-amour-qui-change-le-monde-it\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.explorenicecotedazur.com\/it\/fiche\/exposition-agape-l-amour-qui-change-le-monde-it\/<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition &#8211; La pl\u00e9nitude du vide \u2013 Art du bambou au Japon<\/strong><\/h4>\n<p>Du 27\/07\/2024 au 05\/01\/2025, de 10h \u00e0 17h.<br \/>\nFerm\u00e9 le mardi.<\/p>\n<p>Cette exposition explore l&rsquo;univers du bambou au Japon, un ensemble culturel qui int\u00e8gre l&rsquo;histoire de l&rsquo;archipel, son art et son lien avec la Chine.<\/p>\n<p>Le visiteur d\u00e9couvrira des cr\u00e9ations contemporaines pour ensuite comprendre les racines d&rsquo;une tradition mill\u00e9naire \u00e0 travers un r\u00e9cit articul\u00e9 autour de trois grandes lign\u00e9es d&rsquo;artistes.<\/p>\n<p><a href=\"https:\/\/maa.departement06.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/maa.departement06.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Exposition Jean Mas en ombre et au cube<\/strong><\/h4>\n<p>Du 03\/09\/2024 au 04\/01\/2025, tous les jours.<\/p>\n<p>L&rsquo;Artistique revient avec la restitution de la Collection Donation Ferrero et invite Jean Mas pour une exposition temporaire.<\/p>\n<p>En 1986, Jean Ferrero propose \u00e0 Jean Mas une exposition intitul\u00e9e \u00ab Le cubage de l\u2019\u00c9cole de Nice \u00bb, pour \u00ab cuber \u00bb diff\u00e9rents artistes de l\u2019\u00c9cole de Nice. L\u2019ann\u00e9e suivante, Jean Mas r\u00e9alise 19 cubes en bois de 20x20x20 cm. L&rsquo;exposition se tient avec l&rsquo;\u00e9dition d&rsquo;un livret limit\u00e9 \u00e0 cent exemplaires par \u00ab Z\u2019\u00e9ditions \u00bb, et, comme souvent, lorsque Jean Ferrero est \u00e0 l&rsquo;origine, il d\u00e9cide de conserver toutes ces pi\u00e8ces qui finiront par faire partie de sa donation \u00e0 la Ville de Nice en 2014.<\/p>\n<p><a href=\"https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/l-artistique\" target=\"_new\" rel=\"noopener\">https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/l-artistique<\/a><\/p>\n<hr \/>\n<h4><strong>One Man Show &#8211; Triple dose, Triple fou rire<\/strong><\/h4>\n<p>Du 05\/09 au 05\/12\/2024, le premier jeudi de chaque mois.<\/p>\n<p>Trois com\u00e9diens, trois fois plus de rires !<\/p>\n<p>Pr\u00e9parez-vous \u00e0 vivre une soir\u00e9e explosive avec \u00ab\u00a0Triple dose\u00a0\u00bb ! Chaque premier jeudi du mois, venez d\u00e9couvrir trois com\u00e9diens au talent unique, chacun vous offrant 20 minutes de blagues.<\/p>\n<p>Que vous soyez amateur d\u2019humour noir, de stand-up plus d\u00e9jant\u00e9, ou d\u2019une com\u00e9die plus l\u00e9g\u00e8re, ce spectacle vari\u00e9 saura satisfaire tous les go\u00fbts. Rires garantis !<\/p>\n<p><a href=\"https:\/\/www.explorenicecotedazur.com\/it\/fiche\/triple-dose-triple-fou-rire-it\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.explorenicecotedazur.com\/it\/fiche\/triple-dose-triple-fou-rire-it\/<\/a><\/p>\n<hr \/>\n<h4><strong>Jiv\u00e9jigo<\/strong><\/h4>\n<p>Du 06\/09\/2024 au 05\/07\/2025, le premier vendredi du mois \u00e0 21h.<\/p>\n<p>Une fois par mois, les com\u00e9diens d\u00e9cha\u00een\u00e9s des ContaBlaBla vous proposent le spectacle d\u2019improvisation \u00ab Jiv\u00e9jigo \u00bb.<\/p>\n<p>Depuis 2005, la ligue de th\u00e9\u00e2tre d\u2019improvisation de Nice, les ContaBlaBla, pr\u00e9sente son spectacle d\u2019improvisation \u00ab Jiv\u00e9jigo \u00bb, o\u00f9 l\u2019interaction avec le public est le moteur de la soir\u00e9e !<\/p>\n<p>Quatre acteurs improvisent les histoires les plus inattendues \u00e0 partir des d\u00e9fis impos\u00e9s par un pr\u00e9sentateur d\u00e9cha\u00een\u00e9, qui compte sur la participation active du public pour proposer des mots \u00e0 la vol\u00e9e. Venez donc avec vos id\u00e9es\u2026 Les ContaBlaBla r\u00e9pondront avec les leurs !<\/p>\n<p><a href=\"https:\/\/theatre-impasse.placeminute.com\/event\/improvisation\/jivejigo,36782.html?langue_front=fr\" target=\"_new\" rel=\"noopener\">https:\/\/theatre-impasse.placeminute.com\/event\/improvisation\/jivejigo,36782.html?langue_front=fr<\/a><\/p>\n<hr \/>\n<h4><strong>Ils s\u2019aiment<\/strong><\/h4>\n<p>Il semble que l&rsquo;on appr\u00e9cie les gens pour leurs qualit\u00e9s, mais qu\u2019on les aime pour leurs d\u00e9fauts, et eux, des d\u00e9fauts, ils en ont \u00e0 revendre et n\u2019h\u00e9sitent pas \u00e0 les faire savoir.<\/p>\n<p>Du 07\/09 au 28\/12\/2024, tous les jours.<\/p>\n<p><a href=\"https:\/\/www.billetreduc.com\/v2\/PurchaseTunnel#\/ShowSelection?eventId=308058\" target=\"_new\" rel=\"noopener\">https:\/\/www.billetreduc.com\/v2\/PurchaseTunnel#\/ShowSelection?eventId=308058<\/a><\/p>\n<hr \/>\n<h4><strong>L\u2019Impasse comedy club<\/strong><\/h4>\n<p>Du 11\/09 au 18\/12\/2024, tous les mercredis.<\/p>\n<p>Votre rendez-vous incontournable avec l\u2019humour, chaque mercredi !<\/p>\n<p>L&rsquo;Impasse Comedy Club, le nouveau point de rencontre des passionn\u00e9s de com\u00e9die \u00e0 Nice ! Chaque mercredi, plongez dans une ambiance d\u00e9tendue et venez profiter de deux sessions de stand-up, o\u00f9 humoristes confirm\u00e9s et talents \u00e9mergents se succ\u00e8dent pour vous offrir une soir\u00e9e inoubliable.<\/p>\n<p><a href=\"https:\/\/theatre-impasse.fr\/2024\/08\/20\/limpasse-comedy-club\/\" target=\"_new\" rel=\"noopener\">https:\/\/theatre-impasse.fr\/2024\/08\/20\/limpasse-comedy-club\/<\/a><\/p>\n<hr \/>\n<h4><strong>Sexe, magouilles et culture g\u00e9n\u00e9rale<\/strong><\/h4>\n<p>Du 13\/09\/2024 au 30\/05\/2025, tous les jours.<\/p>\n<p>Spectacle de Laurent Baffie, mise en sc\u00e8ne par S\u00e9bastien Morena.<\/p>\n<p>Pour sauver son jeu t\u00e9l\u00e9vis\u00e9 de culture g\u00e9n\u00e9rale intitul\u00e9 \u00ab\u00a0Culture pour Tous\u00a0\u00bb, dont l&rsquo;audience a chut\u00e9 de 23%, le producteur Franck Petit veut absolument \u00e9liminer Paulette, une candidate tr\u00e8s \u00e2g\u00e9e qui gagne depuis plus de 18 semaines\u2026<\/p>\n<p>Sur le plateau de tournage, Franck Petit est pr\u00eat \u00e0 toutes les ruses et \u00e0 toutes les magouilles avec l&rsquo;accord de Mangin, le pr\u00e9sident de la cha\u00eene, \u00e0 l&rsquo;insu de St\u00e9phane l&rsquo;animateur et J.P. le responsable du plateau&#8230;<\/p>\n<p><a href=\"https:\/\/www.theatrenice.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.theatrenice.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>Toi qui es psy<\/strong><\/h4>\n<p>Du 14\/09\/2024 au 19\/01\/2025, tous les jours.<\/p>\n<p>Un psychologue tr\u00e8s patient et des patients tr\u00e8s psychologiques !<br \/>\nSpectacle th\u00e9\u00e2tral avec S\u00e9bastien Morena.<\/p>\n<p>Un enfant excentrique, une grand-m\u00e8re parano\u00efaque, un psychopathe, une Anglaise baroque et bien d\u2019autres personnages compl\u00e8tement fous ont pris rendez-vous avec le docteur J\u00e9veil dans son cabinet, ouvert aux rires \u00e0 en perdre la t\u00eate !<\/p>\n<p><a href=\"https:\/\/www.theatrenice.fr\/\" target=\"_new\" rel=\"noopener\">https:\/\/www.theatrenice.fr\/<\/a><\/p>\n<hr \/>\n<h4><strong>\u201cAquela Mar \u2013 Cette mer\u201d \u2013 Maurice Maubert<\/strong><\/h4>\n<p>Du 14\/09 au 03\/11\/2024, tous les jours.<\/p>\n<p>Maurice Maubert est Ni\u00e7ois. Il est un enfant du Vieux-Nice, pr\u00e8s du Palais Lascaris. La M\u00e9diterran\u00e9e occupe une place particuli\u00e8re dans son approche artistique.<\/p>\n<p>Dans cette exposition, l\u2019artiste invite \u00e0 renouer avec notre patrimoine commun qu&rsquo;est la mer \u00ab Aquela Mar \u00bb, le titre de l\u2019exposition signifie \u00ab Cette mer \u00bb en ni\u00e7ois.<\/p>\n<p>Cette exposition est divis\u00e9e en trois parties pour une exploration artistique approfondie.<\/p>\n<p><a href=\"https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/palais-lascaris-le-palais\" target=\"_new\" rel=\"noopener\">https:\/\/www.nice.fr\/fr\/culture\/musees-et-galeries\/palais-lascaris-le-palais<\/a><\/p>\n<hr \/>\n<h4><strong>Affaire de bobar<\/strong><\/h4>\n<p>Du 25\/09 au 11\/12\/2024, tous les jours.<\/p>\n<p>Participez \u00e0 l&rsquo;\u00e9v\u00e9nement hilarant \u00ab\u00a0Affaire de Bobar\u00a0\u00bb, le meilleur de l&rsquo;humour proven\u00e7al et de la Riviera !<\/p>\n<p>Affaire de Com\u00e9die, producteur de spectacles de cabaret, qui organise des \u00e9v\u00e9nements dans des lieux atypiques partout dans le sud, arrive pour la premi\u00e8re fois \u00e0 Nice et s&rsquo;associe avec le Bobar Comedy Club, le premier comedy club de Nice !<\/p>\n<p><a href=\"https:\/\/etudiants.nice.fr\/stockfish\/\" target=\"_new\" rel=\"noopener\">https:\/\/etudiants.nice.fr\/stockfish\/<\/a><\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.instagram.com\/monte_carlo_living\/\">Visitez notre page Instagram<\/a><\/p>\n<p><a href=\"https:\/\/montecarloliving.com\/fr\/\">Lisez d&rsquo;autres articles<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!! Atelier de calligraphie japonaise Samedi 2 novembre 2024 \u00e0 14h. \u00c0 l&rsquo;occasion de la pr\u00e9sence \u00e0 Nice des ma\u00eetres calligraphes Kinei Akamatsu et Cheiko Imamura, le Mus\u00e9e des Arts Asiatiques offre au public un moment unique de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[828,868],"tags":[],"class_list":["post-15464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-nice-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice<\/title>\n<meta name=\"description\" content=\"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:title\" content=\"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice\" \/>\n<meta property=\"og:description\" content=\"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/\" \/>\n<meta property=\"og:site_name\" content=\"Montecarlo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montecarlolivingcom\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T08:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montecarloliving.com\/wp-content\/uploads\/2016\/11\/facebook-post-new-650x400.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonteCarloLivi\" \/>\n<meta name=\"twitter:site\" content=\"@MonteCarloLivi\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\"},\"headline\":\"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice\",\"datePublished\":\"2024-11-01T08:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/\"},\"wordCount\":2109,\"image\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/montecarloliving-placeholder.png\",\"articleSection\":[\"\u00c9v\u00e9nements\",\"Nice\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/\",\"name\":\"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/montecarloliving-placeholder.png\",\"datePublished\":\"2024-11-01T08:00:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\"},\"description\":\"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/montecarloliving-placeholder.png\",\"contentUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/montecarloliving-placeholder.png\",\"width\":740,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/nice-fr\\\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/\",\"name\":\"Montecarlo Living\",\"description\":\"News da Montecarlo - Principato di Monaco e Costa Azzurra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice","description":"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/","og_locale":"fr_FR","og_title":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice","og_description":"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...","og_url":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/","og_site_name":"Montecarlo Living","article_publisher":"https:\/\/www.facebook.com\/montecarlolivingcom\/","article_published_time":"2024-11-01T08:00:32+00:00","og_image":[{"width":650,"height":400,"url":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2016\/11\/facebook-post-new-650x400.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@MonteCarloLivi","twitter_site":"@MonteCarloLivi","twitter_misc":{"\u00c9crit par":"Redazione","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#article","isPartOf":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/"},"author":{"name":"Redazione","@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819"},"headline":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice","datePublished":"2024-11-01T08:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/"},"wordCount":2109,"image":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2026\/07\/montecarloliving-placeholder.png","articleSection":["\u00c9v\u00e9nements","Nice"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/","url":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/","name":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice","isPartOf":{"@id":"https:\/\/montecarloliving.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#primaryimage"},"image":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2026\/07\/montecarloliving-placeholder.png","datePublished":"2024-11-01T08:00:32+00:00","author":{"@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819"},"description":"\u00c9v\u00e9nements du week-end \u00e0 Nice, d\u00e9couvrez-les tous!!Atelier de calligraphie japonaiseSamedi 2 novembre 2024 \u00e0 14h...","breadcrumb":{"@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#primaryimage","url":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2026\/07\/montecarloliving-placeholder.png","contentUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2026\/07\/montecarloliving-placeholder.png","width":740,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/montecarloliving.com\/fr\/nice-fr\/evenements-du-week-end-du-2-et-3-novembre-2024-nice-15464\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/montecarloliving.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements du week-end du 2 et 3 novembre 2024 \u00e0 Nice"}]},{"@type":"WebSite","@id":"https:\/\/montecarloliving.com\/fr\/#website","url":"https:\/\/montecarloliving.com\/fr\/","name":"Montecarlo Living","description":"News da Montecarlo - Principato di Monaco e Costa Azzurra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarloliving.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","caption":"Redazione"}}]}},"_links":{"self":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/comments?post=15464"}],"version-history":[{"count":1,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15464\/revisions"}],"predecessor-version":[{"id":15465,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15464\/revisions\/15465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/media\/32465"}],"wp:attachment":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/media?parent=15464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/categories?post=15464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/tags?post=15464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}