{"id":15420,"date":"2024-10-29T11:25:17","date_gmt":"2024-10-29T10:25:17","guid":{"rendered":"https:\/\/montecarloliving.com\/?p=15420"},"modified":"2024-10-29T11:34:04","modified_gmt":"2024-10-29T10:34:04","slug":"foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire","status":"publish","type":"post","link":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/","title":{"rendered":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire"},"content":{"rendered":"<p>Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la <strong>Foire Internationale de la Truffe Blanche d\u2019Alba<\/strong>, l\u2019un des \u00e9v\u00e9nements \u0153nogastronomiques les plus c\u00e9l\u00e8bres et attendus au monde. Cette ann\u00e9e, la foire accueille les visiteurs d\u2019octobre \u00e0 d\u00e9cembre avec un programme d\u2019\u00e9v\u00e9nements qui c\u00e9l\u00e8bre non seulement la truffe blanche, mais aussi le patrimoine culturel, historique et paysager du Pi\u00e9mont.<\/p>\n<h3>La Truffe Blanche d\u2019Alba : L\u2019Or de la Terre<\/h3>\n<p>La truffe blanche d\u2019Alba (<em>Tuber magnatum Pico<\/em>) est l\u2019indiscutable vedette de la foire. R\u00e9put\u00e9e pour son ar\u00f4me intense et unique, elle est consid\u00e9r\u00e9e comme l\u2019un des tr\u00e9sors gastronomiques les plus pr\u00e9cieux au monde, souvent surnomm\u00e9e \u00ab l\u2019or de la terre \u00bb. Sa raret\u00e9 et la m\u00e9thode sp\u00e9cifique de r\u00e9colte, r\u00e9alis\u00e9e avec des chiens dress\u00e9s, contribuent \u00e0 son myst\u00e8re et \u00e0 sa valeur. Lors de la foire, les visiteurs peuvent participer \u00e0 des d\u00e9gustations guid\u00e9es et acheter ce pr\u00e9cieux tubercule directement aupr\u00e8s des trufficulteurs locaux, garantissant ainsi une qualit\u00e9 et une fra\u00eecheur incomparables.<\/p>\n<h3>Le March\u00e9 Mondial de la Truffe et les Ench\u00e8res<\/h3>\n<p>Le <strong>March\u00e9 Mondial de la Truffe Blanche d\u2019Alba<\/strong> est le c\u0153ur de la foire. Situ\u00e9 dans la <strong>Cortile della Maddalena<\/strong>, le march\u00e9 est un lieu o\u00f9 visiteurs, chefs et restaurateurs du monde entier peuvent admirer, acheter et savourer la truffe blanche. Chaque sp\u00e9cimen est soigneusement s\u00e9lectionn\u00e9, \u00e9valu\u00e9 et certifi\u00e9 pour garantir des standards de qualit\u00e9 \u00e9lev\u00e9s.<\/p>\n<p>Un autre moment fort de la foire est la <strong>Vente aux Ench\u00e8res Mondiale de la Truffe Blanche d\u2019Alba<\/strong>, une vente caritative qui attire des participants des quatre coins du monde. Gr\u00e2ce \u00e0 des liaisons satellites, les ench\u00e8res permettent aux collectionneurs du monde entier de remporter les plus grandes et les plus pr\u00e9cieuses truffes, les fonds collect\u00e9s \u00e9tant revers\u00e9s \u00e0 des projets de charit\u00e9.<\/p>\n<h3>Exp\u00e9riences Gastronomiques et Masterclasses<\/h3>\n<p>La Foire de la Truffe Blanche d\u2019Alba est \u00e9galement un lieu de d\u00e9couverte pour les passionn\u00e9s de gastronomie et de vin. Les <strong>analyses sensorielles de la truffe<\/strong>, guid\u00e9es par des truffologues, offrent une exp\u00e9rience unique pour comprendre les caract\u00e9ristiques de la truffe et apprendre \u00e0 la marier au mieux. De plus, les <strong>Masterclasses avec des chefs \u00e9toil\u00e9s<\/strong> permettent aux participants d\u2019apprendre \u00e0 pr\u00e9parer des plats raffin\u00e9s mettant la truffe \u00e0 l\u2019honneur, valorisant ainsi les traditions culinaires locales.<\/p>\n<p>De plus, la foire s\u2019accompagne de d\u00e9gustations de vins des Langhe et du Roero, tels que le Barolo, le Barbaresco et le Nebbiolo, parfaits pour accompagner les plats \u00e0 base de truffe. Cette combinaison entre la truffe et les vins prestigieux de la r\u00e9gion est une opportunit\u00e9 unique pour tous ceux qui souhaitent explorer en profondeur la culture \u0153nologique et gastronomique du Pi\u00e9mont.<\/p>\n<h3>Art, Culture et Territoire<\/h3>\n<p>Parall\u00e8lement \u00e0 la partie gastronomique, la Foire de la Truffe Blanche d\u2019Alba c\u00e9l\u00e8bre la richesse culturelle et artistique du territoire avec des expositions, des spectacles et des visites guid\u00e9es dans les villages des Langhe, patrimoine de l\u2019UNESCO. La foire accueille \u00e9galement des conf\u00e9rences, des ateliers et des rencontres avec des experts et des personnalit\u00e9s de la culture et de la gastronomie, cr\u00e9ant ainsi une exp\u00e9rience compl\u00e8te qui va au-del\u00e0 du simple plaisir gustatif.<\/p>\n<p>De plus, l\u2019attention port\u00e9e \u00e0 la durabilit\u00e9 est l\u2019une des valeurs centrales de la foire. La truffe blanche d\u2019Alba repr\u00e9sente un symbole de la biodiversit\u00e9 des Langhe, et la foire promeut des pratiques de r\u00e9colte et de consommation respectueuses de l\u2019environnement et des traditions locales, contribuant ainsi \u00e0 la pr\u00e9servation d\u2019un produit que les g\u00e9n\u00e9rations futures pourront continuer d\u2019appr\u00e9cier.<\/p>\n<h3>Un \u00c9v\u00e9nement Incontournable<\/h3>\n<p>La Foire Internationale de la Truffe Blanche d\u2019Alba attire des milliers de visiteurs, entre passionn\u00e9s de gastronomie, chefs, restaurateurs et touristes curieux. Avec sa combinaison d\u2019excellence culinaire, de culture et de tradition, elle repr\u00e9sente une occasion unique de d\u00e9couvrir l\u2019authenticit\u00e9 d\u2019un territoire et de s\u2019immerger dans les saveurs et les ar\u00f4mes des Langhe.<\/p>\n<p>Pour ceux qui recherchent une exp\u00e9rience authentique et inoubliable, la Foire de la Truffe Blanche d\u2019Alba est un voyage sensoriel qui c\u00e9l\u00e8bre la beaut\u00e9 de la nature, la tradition culinaire italienne et l\u2019attrait intemporel de l\u2019un des ingr\u00e9dients les plus pr\u00e9cieux au monde.<\/p>\n<p><a href=\"https:\/\/www.fieradeltartufo.org\/\">Fiera Internazionale del Tartufo Bianco d&rsquo;Alba &#8211; Scopri tutti gli eventi<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire Internationale de la Truffe Blanche d\u2019Alba, l\u2019un des \u00e9v\u00e9nements \u0153nogastronomiques les plus c\u00e9l\u00e8bres et attendus au monde. Cette ann\u00e9e, la foire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[828,823],"tags":[],"class_list":["post-15420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-italie-et-monaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire<\/title>\n<meta name=\"description\" content=\"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:title\" content=\"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire\" \/>\n<meta property=\"og:description\" content=\"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/\" \/>\n<meta property=\"og:site_name\" content=\"Montecarlo Living\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montecarlolivingcom\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-29T10:25:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T10:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2-650x400.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonteCarloLivi\" \/>\n<meta name=\"twitter:site\" content=\"@MonteCarloLivi\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\"},\"headline\":\"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire\",\"datePublished\":\"2024-10-29T10:25:17+00:00\",\"dateModified\":\"2024-10-29T10:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/\"},\"wordCount\":805,\"image\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/base-immagine-pulita-2.jpg\",\"articleSection\":[\"\u00c9v\u00e9nements\",\"Italie et Monaco\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/\",\"name\":\"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/base-immagine-pulita-2.jpg\",\"datePublished\":\"2024-10-29T10:25:17+00:00\",\"dateModified\":\"2024-10-29T10:34:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\"},\"description\":\"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/base-immagine-pulita-2.jpg\",\"contentUrl\":\"https:\\\/\\\/montecarloliving.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/base-immagine-pulita-2.jpg\",\"width\":2160,\"height\":1320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/evenements\\\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/\",\"name\":\"Montecarlo Living\",\"description\":\"News da Montecarlo - Principato di Monaco e Costa Azzurra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montecarloliving.com\\\/fr\\\/#\\\/schema\\\/person\\\/7e5945d4560862b7f2d2c6831bda2819\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire","description":"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/","og_locale":"fr_FR","og_title":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire","og_description":"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire","og_url":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/","og_site_name":"Montecarlo Living","article_publisher":"https:\/\/www.facebook.com\/montecarlolivingcom\/","article_published_time":"2024-10-29T10:25:17+00:00","article_modified_time":"2024-10-29T10:34:04+00:00","og_image":[{"width":650,"height":400,"url":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2-650x400.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@MonteCarloLivi","twitter_site":"@MonteCarloLivi","twitter_misc":{"\u00c9crit par":"Redazione","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#article","isPartOf":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/"},"author":{"name":"Redazione","@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819"},"headline":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire","datePublished":"2024-10-29T10:25:17+00:00","dateModified":"2024-10-29T10:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/"},"wordCount":805,"image":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2.jpg","articleSection":["\u00c9v\u00e9nements","Italie et Monaco"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/","url":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/","name":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire","isPartOf":{"@id":"https:\/\/montecarloliving.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#primaryimage"},"image":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#primaryimage"},"thumbnailUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2.jpg","datePublished":"2024-10-29T10:25:17+00:00","dateModified":"2024-10-29T10:34:04+00:00","author":{"@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819"},"description":"Chaque automne, la ville d\u2019Alba, nich\u00e9e parmi les collines des Langhe, devient le centre vibrant de la gastronomie italienne gr\u00e2ce \u00e0 la Foire","breadcrumb":{"@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#primaryimage","url":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2.jpg","contentUrl":"https:\/\/montecarloliving.com\/wp-content\/uploads\/2024\/10\/base-immagine-pulita-2.jpg","width":2160,"height":1320},{"@type":"BreadcrumbList","@id":"https:\/\/montecarloliving.com\/fr\/evenements\/foire-internationale-de-truffe-blanche-dalba-celebration-du-gout-et-du-territoire-15420\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/montecarloliving.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La Foire Internationale de la Truffe Blanche d\u2019Alba : C\u00e9l\u00e9bration du Go\u00fbt et du Territoire"}]},{"@type":"WebSite","@id":"https:\/\/montecarloliving.com\/fr\/#website","url":"https:\/\/montecarloliving.com\/fr\/","name":"Montecarlo Living","description":"News da Montecarlo - Principato di Monaco e Costa Azzurra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montecarloliving.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/montecarloliving.com\/fr\/#\/schema\/person\/7e5945d4560862b7f2d2c6831bda2819","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b5f26557e18fe74ad8e8a57ebb2925d88af8a90cee489ff2beefb391bc9b9c7?s=96&d=mm&r=g","caption":"Redazione"}}]}},"_links":{"self":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/comments?post=15420"}],"version-history":[{"count":2,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15420\/revisions"}],"predecessor-version":[{"id":15423,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/posts\/15420\/revisions\/15423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/media\/15416"}],"wp:attachment":[{"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/media?parent=15420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/categories?post=15420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montecarloliving.com\/fr\/wp-json\/wp\/v2\/tags?post=15420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}